{"id":152,"date":"2017-11-06T23:00:00","date_gmt":"2017-11-06T22:00:00","guid":{"rendered":"https:\/\/www.pecht.info\/wordpress\/2017\/11\/06\/zum-heutigen-100-jahrestag-des-ausbruchs-der-oktoberrevolution\/"},"modified":"2017-11-06T23:00:00","modified_gmt":"2017-11-06T22:00:00","slug":"zum-heutigen-100-jahrestag-des-ausbruchs-der-oktoberrevolution","status":"publish","type":"post","link":"https:\/\/www.pecht.info\/wordpress\/2017\/11\/06\/zum-heutigen-100-jahrestag-des-ausbruchs-der-oktoberrevolution\/","title":{"rendered":"Zum heutigen 100. Jahrestag des &#8222;Ausbruchs der Oktoberrevolution&#8220;"},"content":{"rendered":"<p><strong>ape<\/strong>. Heute vor 100 Jahren. 7. November 1917 (25. Oktober nach julianischem Kalender) = Symboldatum f\u00fcr &#8222;Ausbruch der russischen Oktoberrevolution&#8220;. Bei Durchsicht der medialen Aufbereitung des Themas wird einmal mehr erkennbar: Es gibt in der landl\u00e4ufigen Geschichtsbetrachtung verbreitet eine starke Neigung zu entweder Verkl\u00e4rung oder Aburteilung und Verdammung dieser Revolution, ja bisweilen jedweder Revolution. Letzteres ist zwar verst\u00e4ndlich angesichts der Opfer, die revolution\u00e4re Erhebungen zumeist kosteten, sowie ihrer oft tragischen Folgeentwicklungen. Unter die R\u00e4der ger\u00e4t bei solcher Betrachtungsweise allerdings der zentrale Umstand, dass es zu Revolutionen stets dann kam\/kommt, wenn die Gesellschaftszust\u00e4nde &#8211; vielfach nach Generationen der Bedr\u00fcckung und des Darbens &#8211; zu v\u00f6lliger Unertr\u00e4glichkeit herangereift sind.<\/p>\n<p>Dann gen\u00fcgt oft ein kleiner Funke (zB massive Brotpreiserh\u00f6hung 1789 in Frankreich oder 1918 der Einsatzbefehl an die deutsche Kriegsmarine zu einer sinnlosen letzten Seeschlacht gegen die Royal Navy), das g\u00e4rende Fass explodieren zu lassen. Dann kann auch das entschlossene Vorpreschen einer relativ kleinen Gruppe (wie 1917 der Bolschewiki) gro\u00dfen Menschenmassen Hoffnung auf eine bessere Persepktive geben und sie mitrei\u00dfen. Dass die Revolution nachher wom\u00f6glich ihre Kinder frisst, daran kann und will im Moment des Aufstandes niemand denken. Denn die treibenden und alles dominierenden Kr\u00e4fte des Handelns sind im revolution\u00e4ren Augenblick der Wille, das Unertr\u00e4gliche abzusch\u00fctteln, sowie das Prinzip Hoffnung auf eine bessere Zukunft.<\/p>\n<p>Kurzum: Fast alle bisherigen Revolutionen kamen, weil sie kommen mussten &#8211; ob antike Sklavenerhebungen, mittelalterliche Bauernaufst\u00e4nde, antikoloniale Befreiungskriege, b\u00fcrgerliche Revolutionen im 18.\/19. Jahrhundert, &#8222;sozialistische&#8220; im 20. Jahrhundert oder &#8222;antisozialistische&#8220; ab dessen Sp\u00e4tphase. Wer von heute aus auf die Oktoberrevolution schaut, sollte bei deren Beurteilung auch jener Revolution eingedenk sein, die als Mutter b\u00fcrgerlichen Rechts, b\u00fcrgerlicher Freiheiten, b\u00fcrgerlicher Demokratie gilt: die Franz\u00f6sische Revolution von 1789 &#8211; mit all ihren grausigen Begleiterscheinungen.<\/p>\n<p class=\"rteright\">Andreas Pecht<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ape. Heute vor 100 Jahren. 7. November 1917 (25. Oktober nach julianischem Kalender) = Symboldatum f\u00fcr &#8222;Ausbruch der russischen Oktoberrevolution&#8220;. Bei Durchsicht der medialen Aufbereitung des Themas wird einmal mehr erkennbar: Es gibt in der landl\u00e4ufigen Geschichtsbetrachtung verbreitet eine starke Neigung zu entweder Verkl\u00e4rung oder Aburteilung und Verdammung dieser Revolution, ja bisweilen jedweder Revolution. Letzteres [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"archiv":[18,42],"archiv_inhaltlich":[277,271,270],"class_list":["post-152","post","type-post","status-publish","format-standard","hentry","category-uncategorized","archiv-18","archiv-2017-11","archiv_inhaltlich-geschichte","archiv_inhaltlich-gesellschaft-zeitgeist","archiv_inhaltlich-themen"],"acf":{"bild":"","anhang":""},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/posts\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":0,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/posts\/152\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/media?parent=152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/categories?post=152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/tags?post=152"},{"taxonomy":"archiv","embeddable":true,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/archiv?post=152"},{"taxonomy":"archiv_inhaltlich","embeddable":true,"href":"https:\/\/www.pecht.info\/wordpress\/wp-json\/wp\/v2\/archiv_inhaltlich?post=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}